{"id":1930,"date":"2026-04-14T20:01:59","date_gmt":"2026-04-14T20:01:59","guid":{"rendered":"https:\/\/mamlaketalotor.com\/?post_type=product&#038;p=1930"},"modified":"2026-04-20T17:48:06","modified_gmt":"2026-04-20T17:48:06","slug":"%d8%a8%d9%86%d8%aa-%d8%ad%d9%88%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d8%a3%d8%ad%d9%85%d8%b1","status":"publish","type":"product","link":"https:\/\/mamlaketalotor.com\/en\/product\/%d8%a8%d9%86%d8%aa-%d8%ad%d9%88%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d8%a3%d8%ad%d9%85%d8%b1\/","title":{"rendered":"\u0628\u0646\u062a \u062d\u0648\u0631\u0627\u0646 \u0627\u0644\u0623\u062d\u0645\u0631"},"content":{"rendered":"<p>\u0639\u0637\u0631 \u0646\u0633\u0627\u0626\u064a<\/p>\n<p>\u064a\u062a\u0645\u064a\u0632 \u0628\u062c\u0645\u0627\u0644 \u0627\u0644\u0623\u0632\u0647\u0627\u0631 \u0648 \u062a\u0646\u0627\u063a\u0645 \u0627\u0644\u0632\u064a\u0648\u062a \u0627\u0644\u0623\u0633\u0627\u0633\u064a\u0629 \u0627\u0644\u0641\u0631\u062f\u064a\u0629 \u0644\u0644\u0623\u0634\u062c\u0627\u0631 \u0627\u0644\u062b\u0645\u064a\u0646\u0629 \u0648\u0627\u0644\u062a\u0648\u0627\u0628\u0644 \u0627\u0644\u062f\u0627\u0641\u0626\u0629. \u0639\u0646\u062f\u0645\u0627 \u064a\u062a\u0645 \u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0639\u0637\u0631 \u0628\u0646\u062a \u062d\u0648\u0631\u0627\u0646 \u0627\u0644\u0639\u0631\u0628\u064a \u060c \u0641\u0645\u0646 \u0627\u0644\u0622\u0645\u0646 \u0623\u0646 \u0646\u0642\u0648\u0644 \u0625\u0646 \u0639\u0634\u0627\u0642 \u0627\u0644\u0639\u0637\u0648\u0631 \u0627\u0644\u0639\u0631\u0628 \u0633\u064a\u062a\u0645\u062a\u0639\u0648\u0646 \u0628\u0645\u0632\u064a\u062f \u0645\u0646 \u0627\u0644\u0631\u0642\u064a \u0648\u0627\u0644\u0623\u0646\u0627\u0642\u0629 \u0648\u0627\u0644\u062b\u0642\u0629. \u0627\u062c\u0639\u0644 \u0628\u0646\u062a \u062d\u0648\u0631\u0627\u0646 \u0627\u0633\u0644\u0648\u0628\u0643 \u0641\u0631\u064a\u062f \u0645\u0646 \u0646\u0648\u0639\u0647!<\/p>","protected":false},"excerpt":{"rendered":"<p>\u0639\u0637\u0631 \u0646\u0633\u0627\u0626\u064a<\/p>\n<p>\u064a\u062a\u0645\u064a\u0632 \u0628\u062c\u0645\u0627\u0644 \u0627\u0644\u0623\u0632\u0647\u0627\u0631 \u0648 \u062a\u0646\u0627\u063a\u0645 \u0627\u0644\u0632\u064a\u0648\u062a \u0627\u0644\u0623\u0633\u0627\u0633\u064a\u0629 \u0627\u0644\u0641\u0631\u062f\u064a\u0629 \u0644\u0644\u0623\u0634\u062c\u0627\u0631 \u0627\u0644\u062b\u0645\u064a\u0646\u0629 \u0648\u0627\u0644\u062a\u0648\u0627\u0628\u0644 \u0627\u0644\u062f\u0627\u0641\u0626\u0629. \u0639\u0646\u062f\u0645\u0627 \u064a\u062a\u0645 \u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0639\u0637\u0631 \u0628\u0646\u062a \u062d\u0648\u0631\u0627\u0646 \u0627\u0644\u0639\u0631\u0628\u064a \u060c \u0641\u0645\u0646 \u0627\u0644\u0622\u0645\u0646 \u0623\u0646 \u0646\u0642\u0648\u0644 \u0625\u0646 \u0639\u0634\u0627\u0642 \u0627\u0644\u0639\u0637\u0648\u0631 \u0627\u0644\u0639\u0631\u0628 \u0633\u064a\u062a\u0645\u062a\u0639\u0648\u0646 \u0628\u0645\u0632\u064a\u062f \u0645\u0646 \u0627\u0644\u0631\u0642\u064a \u0648\u0627\u0644\u0623\u0646\u0627\u0642\u0629 \u0648\u0627\u0644\u062b\u0642\u0629. \u0627\u062c\u0639\u0644 \u0628\u0646\u062a \u062d\u0648\u0631\u0627\u0646 \u0627\u0633\u0644\u0648\u0628\u0643 \u0641\u0631\u064a\u062f \u0645\u0646 \u0646\u0648\u0639\u0647!<\/p>","protected":false},"featured_media":1931,"comment_status":"open","ping_status":"closed","template":"","meta":{"_angie_page":false,"_eb_attr":"","_oliver_stock_3302":0,"_oliver_low_stock_3302":0,"_oliver_barcode":"","_oliver_pos_exclude":"no","_oliver_pos_fulfillment_instructions":"","_oliver_pos_prep_time":0,"_oliver_pos_fulfillment_category":"","_oliver_pos_prompt_notes":"no","_oliver_pos_kds_priority":"normal","_oliver_pos_fulfillment_image":0},"product_brand":[],"product_cat":[81,77],"product_tag":[],"class_list":{"0":"post-1930","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-81","7":"product_cat-77","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0628\u0646\u062a \u062d\u0648\u0631\u0627\u0646 \u0627\u0644\u0623\u062d\u0645\u0631 - \u0645\u0645\u0644\u0643\u0629 \u0627\u0644\u0639\u0637\u0648\u0631<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mamlaketalotor.com\/en\/product\/\u0628\u0646\u062a-\u062d\u0648\u0631\u0627\u0646-\u0627\u0644\u0623\u062d\u0645\u0631\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0628\u0646\u062a \u062d\u0648\u0631\u0627\u0646 \u0627\u0644\u0623\u062d\u0645\u0631 - \u0645\u0645\u0644\u0643\u0629 \u0627\u0644\u0639\u0637\u0648\u0631\" \/>\n<meta property=\"og:description\" content=\"\u0639\u0637\u0631 \u0646\u0633\u0627\u0626\u064a  \u064a\u062a\u0645\u064a\u0632 \u0628\u062c\u0645\u0627\u0644 \u0627\u0644\u0623\u0632\u0647\u0627\u0631 \u0648 \u062a\u0646\u0627\u063a\u0645 \u0627\u0644\u0632\u064a\u0648\u062a \u0627\u0644\u0623\u0633\u0627\u0633\u064a\u0629 \u0627\u0644\u0641\u0631\u062f\u064a\u0629 \u0644\u0644\u0623\u0634\u062c\u0627\u0631 \u0627\u0644\u062b\u0645\u064a\u0646\u0629 \u0648\u0627\u0644\u062a\u0648\u0627\u0628\u0644 \u0627\u0644\u062f\u0627\u0641\u0626\u0629. \u0639\u0646\u062f\u0645\u0627 \u064a\u062a\u0645 \u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0639\u0637\u0631 \u0628\u0646\u062a \u062d\u0648\u0631\u0627\u0646 \u0627\u0644\u0639\u0631\u0628\u064a \u060c \u0641\u0645\u0646 \u0627\u0644\u0622\u0645\u0646 \u0623\u0646 \u0646\u0642\u0648\u0644 \u0625\u0646 \u0639\u0634\u0627\u0642 \u0627\u0644\u0639\u0637\u0648\u0631 \u0627\u0644\u0639\u0631\u0628 \u0633\u064a\u062a\u0645\u062a\u0639\u0648\u0646 \u0628\u0645\u0632\u064a\u062f \u0645\u0646 \u0627\u0644\u0631\u0642\u064a \u0648\u0627\u0644\u0623\u0646\u0627\u0642\u0629 \u0648\u0627\u0644\u062b\u0642\u0629. \u0627\u062c\u0639\u0644 \u0628\u0646\u062a \u062d\u0648\u0631\u0627\u0646 \u0627\u0633\u0644\u0648\u0628\u0643 \u0641\u0631\u064a\u062f \u0645\u0646 \u0646\u0648\u0639\u0647!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mamlaketalotor.com\/en\/product\/\u0628\u0646\u062a-\u062d\u0648\u0631\u0627\u0646-\u0627\u0644\u0623\u062d\u0645\u0631\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0645\u0645\u0644\u0643\u0629 \u0627\u0644\u0639\u0637\u0648\u0631\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-20T17:48:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mamlaketalotor.com\/wp-content\/uploads\/2026\/04\/500949236_1805233673578531_1280903138847817309_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mamlaketalotor.com\\\/product\\\/%d8%a8%d9%86%d8%aa-%d8%ad%d9%88%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d8%a3%d8%ad%d9%85%d8%b1\\\/\",\"url\":\"https:\\\/\\\/mamlaketalotor.com\\\/product\\\/%d8%a8%d9%86%d8%aa-%d8%ad%d9%88%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d8%a3%d8%ad%d9%85%d8%b1\\\/\",\"name\":\"\u0628\u0646\u062a \u062d\u0648\u0631\u0627\u0646 \u0627\u0644\u0623\u062d\u0645\u0631 - \u0645\u0645\u0644\u0643\u0629 \u0627\u0644\u0639\u0637\u0648\u0631\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mamlaketalotor.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mamlaketalotor.com\\\/product\\\/%d8%a8%d9%86%d8%aa-%d8%ad%d9%88%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d8%a3%d8%ad%d9%85%d8%b1\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mamlaketalotor.com\\\/product\\\/%d8%a8%d9%86%d8%aa-%d8%ad%d9%88%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d8%a3%d8%ad%d9%85%d8%b1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mamlaketalotor.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/500949236_1805233673578531_1280903138847817309_n.jpg\",\"datePublished\":\"2026-04-14T20:01:59+00:00\",\"dateModified\":\"2026-04-20T17:48:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mamlaketalotor.com\\\/product\\\/%d8%a8%d9%86%d8%aa-%d8%ad%d9%88%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d8%a3%d8%ad%d9%85%d8%b1\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mamlaketalotor.com\\\/product\\\/%d8%a8%d9%86%d8%aa-%d8%ad%d9%88%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d8%a3%d8%ad%d9%85%d8%b1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mamlaketalotor.com\\\/product\\\/%d8%a8%d9%86%d8%aa-%d8%ad%d9%88%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d8%a3%d8%ad%d9%85%d8%b1\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mamlaketalotor.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/500949236_1805233673578531_1280903138847817309_n.jpg\",\"contentUrl\":\"https:\\\/\\\/mamlaketalotor.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/500949236_1805233673578531_1280903138847817309_n.jpg\",\"width\":1024,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mamlaketalotor.com\\\/product\\\/%d8%a8%d9%86%d8%aa-%d8%ad%d9%88%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d8%a3%d8%ad%d9%85%d8%b1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629\",\"item\":\"https:\\\/\\\/mamlaketalotor.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/mamlaketalotor.com\\\/en\\\/shop-2\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0628\u0646\u062a \u062d\u0648\u0631\u0627\u0646 \u0627\u0644\u0623\u062d\u0645\u0631\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mamlaketalotor.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/mamlaketalotor.com\\\/en\\\/\",\"name\":\"\u0645\u0645\u0644\u0643\u0629 \u0627\u0644\u0639\u0637\u0648\u0631\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/mamlaketalotor.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mamlaketalotor.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mamlaketalotor.com\\\/en\\\/#organization\",\"name\":\"\u0645\u0645\u0644\u0643\u0629 \u0627\u0644\u0639\u0637\u0648\u0631\",\"url\":\"https:\\\/\\\/mamlaketalotor.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mamlaketalotor.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mamlaketalotor.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/ff-copy.png\",\"contentUrl\":\"https:\\\/\\\/mamlaketalotor.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/ff-copy.png\",\"width\":500,\"height\":500,\"caption\":\"\u0645\u0645\u0644\u0643\u0629 \u0627\u0644\u0639\u0637\u0648\u0631\"},\"image\":{\"@id\":\"https:\\\/\\\/mamlaketalotor.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0628\u0646\u062a \u062d\u0648\u0631\u0627\u0646 \u0627\u0644\u0623\u062d\u0645\u0631 - \u0645\u0645\u0644\u0643\u0629 \u0627\u0644\u0639\u0637\u0648\u0631","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mamlaketalotor.com\/en\/product\/\u0628\u0646\u062a-\u062d\u0648\u0631\u0627\u0646-\u0627\u0644\u0623\u062d\u0645\u0631\/","og_locale":"en_US","og_type":"article","og_title":"\u0628\u0646\u062a \u062d\u0648\u0631\u0627\u0646 \u0627\u0644\u0623\u062d\u0645\u0631 - \u0645\u0645\u0644\u0643\u0629 \u0627\u0644\u0639\u0637\u0648\u0631","og_description":"\u0639\u0637\u0631 \u0646\u0633\u0627\u0626\u064a  \u064a\u062a\u0645\u064a\u0632 \u0628\u062c\u0645\u0627\u0644 \u0627\u0644\u0623\u0632\u0647\u0627\u0631 \u0648 \u062a\u0646\u0627\u063a\u0645 \u0627\u0644\u0632\u064a\u0648\u062a \u0627\u0644\u0623\u0633\u0627\u0633\u064a\u0629 \u0627\u0644\u0641\u0631\u062f\u064a\u0629 \u0644\u0644\u0623\u0634\u062c\u0627\u0631 \u0627\u0644\u062b\u0645\u064a\u0646\u0629 \u0648\u0627\u0644\u062a\u0648\u0627\u0628\u0644 \u0627\u0644\u062f\u0627\u0641\u0626\u0629. \u0639\u0646\u062f\u0645\u0627 \u064a\u062a\u0645 \u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0639\u0637\u0631 \u0628\u0646\u062a \u062d\u0648\u0631\u0627\u0646 \u0627\u0644\u0639\u0631\u0628\u064a \u060c \u0641\u0645\u0646 \u0627\u0644\u0622\u0645\u0646 \u0623\u0646 \u0646\u0642\u0648\u0644 \u0625\u0646 \u0639\u0634\u0627\u0642 \u0627\u0644\u0639\u0637\u0648\u0631 \u0627\u0644\u0639\u0631\u0628 \u0633\u064a\u062a\u0645\u062a\u0639\u0648\u0646 \u0628\u0645\u0632\u064a\u062f \u0645\u0646 \u0627\u0644\u0631\u0642\u064a \u0648\u0627\u0644\u0623\u0646\u0627\u0642\u0629 \u0648\u0627\u0644\u062b\u0642\u0629. \u0627\u062c\u0639\u0644 \u0628\u0646\u062a \u062d\u0648\u0631\u0627\u0646 \u0627\u0633\u0644\u0648\u0628\u0643 \u0641\u0631\u064a\u062f \u0645\u0646 \u0646\u0648\u0639\u0647!","og_url":"https:\/\/mamlaketalotor.com\/en\/product\/\u0628\u0646\u062a-\u062d\u0648\u0631\u0627\u0646-\u0627\u0644\u0623\u062d\u0645\u0631\/","og_site_name":"\u0645\u0645\u0644\u0643\u0629 \u0627\u0644\u0639\u0637\u0648\u0631","article_modified_time":"2026-04-20T17:48:06+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/mamlaketalotor.com\/wp-content\/uploads\/2026\/04\/500949236_1805233673578531_1280903138847817309_n.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mamlaketalotor.com\/product\/%d8%a8%d9%86%d8%aa-%d8%ad%d9%88%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d8%a3%d8%ad%d9%85%d8%b1\/","url":"https:\/\/mamlaketalotor.com\/product\/%d8%a8%d9%86%d8%aa-%d8%ad%d9%88%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d8%a3%d8%ad%d9%85%d8%b1\/","name":"\u0628\u0646\u062a \u062d\u0648\u0631\u0627\u0646 \u0627\u0644\u0623\u062d\u0645\u0631 - \u0645\u0645\u0644\u0643\u0629 \u0627\u0644\u0639\u0637\u0648\u0631","isPartOf":{"@id":"https:\/\/mamlaketalotor.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mamlaketalotor.com\/product\/%d8%a8%d9%86%d8%aa-%d8%ad%d9%88%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d8%a3%d8%ad%d9%85%d8%b1\/#primaryimage"},"image":{"@id":"https:\/\/mamlaketalotor.com\/product\/%d8%a8%d9%86%d8%aa-%d8%ad%d9%88%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d8%a3%d8%ad%d9%85%d8%b1\/#primaryimage"},"thumbnailUrl":"https:\/\/mamlaketalotor.com\/wp-content\/uploads\/2026\/04\/500949236_1805233673578531_1280903138847817309_n.jpg","datePublished":"2026-04-14T20:01:59+00:00","dateModified":"2026-04-20T17:48:06+00:00","breadcrumb":{"@id":"https:\/\/mamlaketalotor.com\/product\/%d8%a8%d9%86%d8%aa-%d8%ad%d9%88%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d8%a3%d8%ad%d9%85%d8%b1\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mamlaketalotor.com\/product\/%d8%a8%d9%86%d8%aa-%d8%ad%d9%88%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d8%a3%d8%ad%d9%85%d8%b1\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mamlaketalotor.com\/product\/%d8%a8%d9%86%d8%aa-%d8%ad%d9%88%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d8%a3%d8%ad%d9%85%d8%b1\/#primaryimage","url":"https:\/\/mamlaketalotor.com\/wp-content\/uploads\/2026\/04\/500949236_1805233673578531_1280903138847817309_n.jpg","contentUrl":"https:\/\/mamlaketalotor.com\/wp-content\/uploads\/2026\/04\/500949236_1805233673578531_1280903138847817309_n.jpg","width":1024,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/mamlaketalotor.com\/product\/%d8%a8%d9%86%d8%aa-%d8%ad%d9%88%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d8%a3%d8%ad%d9%85%d8%b1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629","item":"https:\/\/mamlaketalotor.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/mamlaketalotor.com\/en\/shop-2\/"},{"@type":"ListItem","position":3,"name":"\u0628\u0646\u062a \u062d\u0648\u0631\u0627\u0646 \u0627\u0644\u0623\u062d\u0645\u0631"}]},{"@type":"WebSite","@id":"https:\/\/mamlaketalotor.com\/en\/#website","url":"https:\/\/mamlaketalotor.com\/en\/","name":"\u0645\u0645\u0644\u0643\u0629 \u0627\u0644\u0639\u0637\u0648\u0631","description":"","publisher":{"@id":"https:\/\/mamlaketalotor.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mamlaketalotor.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/mamlaketalotor.com\/en\/#organization","name":"\u0645\u0645\u0644\u0643\u0629 \u0627\u0644\u0639\u0637\u0648\u0631","url":"https:\/\/mamlaketalotor.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mamlaketalotor.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/mamlaketalotor.com\/wp-content\/uploads\/2026\/04\/ff-copy.png","contentUrl":"https:\/\/mamlaketalotor.com\/wp-content\/uploads\/2026\/04\/ff-copy.png","width":500,"height":500,"caption":"\u0645\u0645\u0644\u0643\u0629 \u0627\u0644\u0639\u0637\u0648\u0631"},"image":{"@id":"https:\/\/mamlaketalotor.com\/en\/#\/schema\/logo\/image\/"}}]}},"_cost_price":"","_links":{"self":[{"href":"https:\/\/mamlaketalotor.com\/en\/wp-json\/wp\/v2\/product\/1930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mamlaketalotor.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mamlaketalotor.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/mamlaketalotor.com\/en\/wp-json\/wp\/v2\/comments?post=1930"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mamlaketalotor.com\/en\/wp-json\/wp\/v2\/media\/1931"}],"wp:attachment":[{"href":"https:\/\/mamlaketalotor.com\/en\/wp-json\/wp\/v2\/media?parent=1930"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mamlaketalotor.com\/en\/wp-json\/wp\/v2\/product_brand?post=1930"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mamlaketalotor.com\/en\/wp-json\/wp\/v2\/product_cat?post=1930"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mamlaketalotor.com\/en\/wp-json\/wp\/v2\/product_tag?post=1930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}